{"id":13559,"date":"2020-09-16T20:49:59","date_gmt":"2020-09-17T04:49:59","guid":{"rendered":"https:\/\/thegirlwrites.com\/?p=13559"},"modified":"2020-09-28T10:30:33","modified_gmt":"2020-09-28T18:30:33","slug":"postpartum-depression-a-new-perspective-on-maternity","status":"publish","type":"post","link":"https:\/\/thegirlwrites.com\/pt\/postpartum-depression-a-new-perspective-on-maternity\/","title":{"rendered":"Depress\u00e3o p\u00f3s-parto: Uma nova perspectiva sobre a maternidade"},"content":{"rendered":"<p>Um dos fatores de risco ou predisponentes para o desenvolvimento da depress\u00e3o p\u00f3s-parto (DPP), \u00e9 a <em>idealiza\u00e7\u00e3o da maternidade. <\/em>A maternidade \u00e9 sempre apresentada cheia de felicidade, contentamento, alegria e paz. Sim, \u00e9 uma fase linda e repleta de b\u00ean\u00e7\u00e3os, mas \u00e9 tamb\u00e9m cheia de dificuldades, priva\u00e7\u00f5es e pode ter muitas dores f\u00edsicas e emocionais. Quanto menos consciente e preparada a mulher estiver, maiores as chances de frustra\u00e7\u00e3o e adoecimento ps\u00edquico. Alguns grupos de m\u00e3es est\u00e3o, especialmente, sujeitas a desenvolverem a depress\u00e3o p\u00f3s-parto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mulheres que passam por \u00f3tima gesta\u00e7\u00e3o<\/h3>\n\n\n\n<p>Existem mulheres que passam a gravidez toda super tranquilas e, por isso criam expectativas de um p\u00f3s-parto igualmente feliz. Mas, o puerp\u00e9rio, a amamenta\u00e7\u00e3o, a priva\u00e7\u00e3o do sono, as dores do parto e outros conflitos, podem dar um choque de realidade nessa m\u00e3e e ela adoecer emocionalmente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mulheres que passam por tratamentos fertilizantes<\/h3>\n\n\n\n<p>Fatores f\u00edsicos, emocionais ou circunstanciais podem impedir uma gravidez e muitas vezes o casal opta por procedimentos cl\u00ednicos para a realiza\u00e7\u00e3o do sonho de gerar um filho. Quanto mais dif\u00edcil for engravidar, maiores as expectativas com rela\u00e7\u00e3o \u00e0 gesta\u00e7\u00e3o, p\u00f3s-parto e mesmo da pr\u00f3pria crian\u00e7a. E novamente, todas as intercorr\u00eancias podem gerar frustra\u00e7\u00e3o e tristeza, desenvolvendo por fim, a depress\u00e3o p\u00f3s-parto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mulheres que engravidam com idade avan\u00e7ada<\/h3>\n\n\n\n<p>Muitas mulheres planejam ter filhos somente ap\u00f3s terem conquistado v\u00e1rios sonhos pessoais e profissionais. Ser m\u00e3e acaba sendo a conquista final, a cereja do bolo de uma vida bem-sucedida e feliz. Mas, as dificuldades e priva\u00e7\u00f5es que a maternidade traz, podem servir de fatores de tristeza e desapontamento, levando essa mulher ao arrependimento e depress\u00e3o p\u00f3s-parto.<\/p>\n\n\n\n<p>Al\u00e9m desses grupos, fatores como o puerp\u00e9rio, o eterno senso de responsabilidade, a falta de liberdade - em especial nos primeiros anos - os novos desafios e dificuldades apresentados pelo exerc\u00edcio da maternidade, e a necessidade de adapta\u00e7\u00e3o para dar continuidade a vida, podem levar muitas mulheres \u00e0 frustra\u00e7\u00e3o e tristeza t\u00e3o grandes que elas acabam por adoecer e desenvolver a depress\u00e3o p\u00f3s-parto. Por isso, \u00e9 importante o preparo emocional no pr\u00e9-natal e suporte social no p\u00f3s-parto, para que a m\u00e3e possa superar as dificuldades da forma mais leve poss\u00edvel e que, as tristezas e dores n\u00e3o tenham peso maior que as alegrias e felicidades encontradas no exerc\u00edcio da maternidade.<\/p>\n\n\n\n<p>Como exemplo, segue meu pr\u00f3prio relato de parto: Eu sabia que minha vida mudaria quando minha filha nascesse, mas como sempre fui ativa e gosto de estudar, achei que logo conseguiria retomar minhas atividades, mas a realidade foi diferente. Passei dias inteiros com minha filha no colo, cuidando, amamentando e quando ela finalmente dormia, eu estava exausta e s\u00f3 queria descansar. Vivi muitos dias frustrada e triste, me sentindo in\u00fatil, com a sensa\u00e7\u00e3o de n\u00e3o ter feito nada o dia todo. Tive momentos em que s\u00f3 chorava e queria sumir, ent\u00e3o entendi que, se n\u00e3o mudasse meu modo de ver as coisas, adoeceria emocionalmente. <\/p>\n\n\n\n<p>Comecei a ler no celular os escritos de Ellen White sobre maternidade e textos sobre desenvolvimento infantil. Criei um 'mantra' na minha mente: <\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/thegirlwrites.com\/wp-content\/uploads\/2020\/09\/Social-Bio-12.jpg\" alt=\"Women susceptible to postpartum depression\" class=\"wp-image-13573\" srcset=\"https:\/\/thegirlwrites.com\/wp-content\/uploads\/2020\/09\/Social-Bio-12.jpg 1024w, https:\/\/thegirlwrites.com\/wp-content\/uploads\/2020\/09\/Social-Bio-12-300x300.jpg 300w, https:\/\/thegirlwrites.com\/wp-content\/uploads\/2020\/09\/Social-Bio-12-150x150.jpg 150w, https:\/\/thegirlwrites.com\/wp-content\/uploads\/2020\/09\/Social-Bio-12-768x768.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-normal-font-size\"><strong>\"O tempo gasto com minha filha, nunca \u00e9 perdido. Passar o dia com ela no colo, n\u00e3o \u00e9 tempo perdido. Afeto nunca \u00e9 demais. Estou construindo as bases da vida ps\u00edquica de um ser humano\".<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Comecei a conversar com outras m\u00e3es e senti que n\u00e3o estava sozinha, pois muitas compartilham desse sentimento. Isso acalentou meu cora\u00e7\u00e3o e me ajudou a ressignificar meus dias. Hoje, n\u00e3o me cobro em produzir, realizar tarefas ou ter pressa para viver meus sonhos. Tenho consci\u00eancia que minha vida nunca mais ser\u00e1 a mesma, mas a prioridade \u00e9 minha filha que logo vai crescer e terei tempo para coisas menos importantes. Vivo um dia de cada vez, aproveitando cada minuto com ela e confiando que Deus prover\u00e1 todas as coisas.<\/p>\n\n\n\n<p class=\"translation-block\">Read the other articles in our <em>The Baby\u2019s Here! Now What?<\/em> series!<\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/thegirlwrites.com\/pt\/postpartum-depression-a-new-perspective-on-maternity\/\" data-type=\"URL\" data-id=\"https:\/\/thegirlwrites.com\/postpartum-depression-a-new-perspective-on-maternity\/\" target=\"_blank\">Intro to Breastfeeding for the Expectant Mother<\/a><\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/thegirlwrites.com\/pt\/mirror-mirror-loving-your-body-postpartum\/\" target=\"_blank\">Espelho, espelho meu: amando seu corpo p\u00f3s-parto<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/thegirlwrites.com\/pt\/unsolicited-advice\/\" data-type=\"post\" data-id=\"13264\" target=\"_blank\" rel=\"noreferrer noopener\">Opini\u00e3o n\u00e3o contratada: o que fazer?<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabia que existem grupos espec\u00edficos de mulheres em maior risco de desenvolver depress\u00e3o p\u00f3s-parto? H\u00e1 tamb\u00e9m certos fatores que s\u00f3 por estar ciente, voc\u00ea pode mitigar!<\/p>","protected":false},"author":14,"featured_media":13565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"Did you know that there are specific groups of women at higher risk for developing postpartum depression? There are also certain factors that just by being aware of, you can mitigate!","_seopress_robots_index":"","_seopress_analysis_target_kw":"postpartum depression meaning,who&#039;s at risk for postpartum depression,factors that contribute to postpartum depression,Christian motherhood,how to have a healthy pregnancy","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1782,1784,1780],"tags":[],"lang":[1775],"class_list":["post-13559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-family","category-health","category-relationships","lang-english"],"_links":{"self":[{"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/posts\/13559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/comments?post=13559"}],"version-history":[{"count":5,"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/posts\/13559\/revisions"}],"predecessor-version":[{"id":13846,"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/posts\/13559\/revisions\/13846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/media\/13565"}],"wp:attachment":[{"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/media?parent=13559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/categories?post=13559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/tags?post=13559"},{"taxonomy":"lang","embeddable":true,"href":"https:\/\/thegirlwrites.com\/pt\/wp-json\/wp\/v2\/lang?post=13559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}